{"id":35,"date":"2025-09-01T19:17:58","date_gmt":"2025-09-01T17:17:58","guid":{"rendered":"https:\/\/www.ac-acustica.it\/new\/?page_id=35"},"modified":"2026-08-06T14:41:16","modified_gmt":"2026-08-06T12:41:16","slug":"about","status":"publish","type":"page","link":"https:\/\/www.ac-acustica.it\/en\/about","title":{"rendered":"About","raw":"About"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-c4787d8b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-5d8c8575\">\n<p class=\"wp-block-paragraph\"><strong>AC Acustica<\/strong> offers acoustic design and consulting services in the fields of engineering and architecture, combining international experience and advanced technologies to ensure innovative and precise solutions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Based in <strong>Ragusa<\/strong>, AC Acustica is led by <strong>Andrea Cicero<\/strong>, who holds a degree in Civil Engineering and a specialization in Acoustics and Audio from the University of Salford. He has many years of experience in the field of acoustics and vibrations, having worked at one of the leading acoustic design and consultancy firms in London, United Kingdom.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-82324d6c\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/andrea-cicero-1024x766.jpg\" alt=\"\" class=\"wp-image-334\" style=\"border-radius:10px;box-shadow:none\" srcset=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/andrea-cicero-1024x766.jpg 1024w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/andrea-cicero-300x225.jpg 300w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/andrea-cicero-768x575.jpg 768w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/andrea-cicero.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-814f3dd2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-61d2d51f\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/profilo-1-1024x576.jpg\" alt=\"\" class=\"wp-image-344\" style=\"border-radius:10px;box-shadow:none\" srcset=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/profilo-1-1024x576.jpg 1024w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/profilo-1-300x169.jpg 300w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/profilo-1-768x432.jpg 768w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/profilo-1-1536x864.jpg 1536w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/profilo-1.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d17045e1\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7e559186\"><h3 class=\"uagb-heading-text\">Awards<\/h3><p class=\"uagb-desc-text\">Italian Acoustical Society \u2018<strong>Young Professionals\u2019 Award 2024<\/strong>, on the occasion of the National Conference in Taormina, for the work <em><a href=\"https:\/\/www.francoangeli.it\/riviste\/articolo\/76817\"><span style=\"text-decoration: underline;\">Acoustic Design of a Modular Studio Box for Use as Control and Mixing Room for Immersive Audio<\/span><\/a><\/em><\/p><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b4af9fd3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-49b0479c\"><h3 class=\"uagb-heading-text\">Technical Skills and Instrumentation<\/h3><p class=\"uagb-desc-text\">AC Acustica is equipped with state-of-the-art certified instrumentation to ensure precise and reliable measurements.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-54c0b8e2\"><h3 class=\"uagb-heading-text\">Acustic Instumentation<\/h3><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>6 Class 1 sound level meters compliant with IEC 61672<\/strong> for professional measurements in architectural, building, environmental, and industrial acoustics<\/li>\n\n\n\n<li><strong>3 accelerometric measurement chains compliant with ISO 8041-1:2017<\/strong> for measurements related to vibration disturbance, building damage assessment, and exposure to mechanical vibrations.<\/li>\n\n\n\n<li><strong>Specialized accessories<\/strong> for long-term acoustic and vibration monitoring<\/li>\n\n\n\n<li><strong>Impulse response measurement kit<\/strong> dedicated to architectural acoustics<\/li>\n\n\n\n<li><strong>Calibrated omnidirectional dodecahedral sound source<\/strong> for measurements of sound insulation and room acoustic parameters.<\/li>\n\n\n\n<li><strong>Tapping machine<\/strong> for testing impact sound insulation<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ef732557\"><h3 class=\"uagb-heading-text\">Specialized software<\/h3><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>CATT-Acoustic<\/strong> for advanced architectural acoustic modeling<\/li>\n\n\n\n<li><strong>iNoise Pro<\/strong> for environmental noise impact assessments<\/li>\n\n\n\n<li><strong>Insul<\/strong> for sound insulation calculations<\/li>\n\n\n\n<li><strong>Audieum<\/strong> \u2013 proprietary software for analysis and modeling of critical listening environments<\/li>\n\n\n\n<li><strong>Custom algorithms<\/strong> for advanced data analysis and process optimization<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-47ae6514 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-041f12c1\"><h3 class=\"uagb-heading-text\">Certifications and Affiliations<\/h3><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Membership in <strong>Ordine degli Ingegneri della Provincia di Ragusa<\/strong><\/li>\n\n\n\n<li><strong>Competent Acoustic Technician<\/strong> registered with ENTECA under no. 306<\/li>\n\n\n\n<li>Member of:\n<ul class=\"wp-block-list\">\n<li><strong>Audio Engineering Society (AES)<\/strong><\/li>\n\n\n\n<li><strong>Institute of Acoustics (IOA)<\/strong><\/li>\n\n\n\n<li><strong>Associazione Italiana di Acustica (AIA)<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-59970e4e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-9d6e21ec\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-68465e67\"><h3 class=\"uagb-heading-text\">Rete Acustici<\/h3><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Andrea Cicero is the founder of <strong>Rete Acustici<\/strong> (<a href=\"https:\/\/reteacustici.it\" type=\"link\" id=\"reteacustici.it\">reteacustici.it<\/a>), a <strong>collaborative digital platform<\/strong> that brings together Italian professionals in the field of acoustics. This initiative promotes technical exchange, professional discussion, and mutual support among acoustic consultants, technicians, and engineers, strengthening a nationwide network of specialized expertise.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-570142a0\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/reteacustici.it\/img\/LOGO%20RETE%20ACUSTICI_blu.png\" alt=\"Rete Acustici\" style=\"object-fit:cover\"\/><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-hide-mob uagb-block-69066129 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b40c0c24\"><h3 class=\"uagb-heading-text\">Partners<\/h3><\/div>\n\n\n\n<div class=\"wp-block-lcb-logo-carousel alcb-block-lm6khjkq\"><div dir=\"ltr\" class=\"alcb__carousel_container swiper\" data-desktop=\"5\" data-tablet=\"3\" data-mobile=\"3\" data-autoplay=\"true\" data-autoplaydelay=\"2000\" data-autoplaydirection=\"false\" data-speed=\"400\" data-loop=\"true\" data-pauseonhover=\"true\" data-keyboard=\"false\" data-mousewheel=\"false\" data-autoheight=\"false\" data-deskspace=\"10\" data-tabspace=\"10\" data-phonespace=\"10\" data-id=\"alcb-block-lm6khjkq\" data-pagination=\"false\" data-navigation=\"false\" id=\"alcb-block-lm6khjkq\"><div class=\"swiper-wrapper\"><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/reteacustici.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\" alt=\"\" id=\"751\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.acusticambientale.com\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\" alt=\"\" id=\"641\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/eupro.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\" alt=\"\" id=\"642\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.hackustica.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\" alt=\"\" id=\"750\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"http:\/\/www.accon.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\" alt=\"\" id=\"925\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/sonnite.com\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\" alt=\"\" id=\"1009\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.redsound.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img decoding=\"async\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\" alt=\"\" id=\"643\"\/><\/div><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-4a35580c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5cda3c4b\"><h3 class=\"uagb-heading-text\">Partners<\/h3><\/div>\n\n\n\n<div class=\"wp-block-lcb-grid-logo alcb-block-af92yq7u grid-logos\"><div class=\"gallery-inner\">\n<div class=\"wp-block-lcb-logo alcb-block-sekgmses\"><a href=\"https:\/\/reteacustici.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"200\" class=\"wp-image-751\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\" srcset=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg 350w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n\n\n\n<div class=\"wp-block-lcb-logo alcb-block-46fx8plw\"><a href=\"https:\/\/www.acusticambientale.com\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"200\" class=\"wp-image-641\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\" srcset=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg 350w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n\n\n\n<div class=\"wp-block-lcb-logo alcb-block-0bhryuli\"><a href=\"https:\/\/eupro.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"200\" class=\"wp-image-642\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\" srcset=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg 350w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n\n\n\n<div class=\"wp-block-lcb-logo alcb-block-q9pyvor4\"><a href=\"https:\/\/www.hackustica.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"200\" class=\"wp-image-750\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\" srcset=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg 350w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n\n\n\n<div class=\"wp-block-lcb-logo alcb-block-ghnx2530\"><a href=\"http:\/\/www.accon.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"200\" class=\"wp-image-925\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\" srcset=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg 350w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n\n\n\n<div class=\"wp-block-lcb-logo alcb-block-29ok4l8i\"><a href=\"https:\/\/sonnite.com\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"200\" class=\"wp-image-1016\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\" srcset=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg 350w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-300x171.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n\n\n\n<div class=\"wp-block-lcb-logo alcb-block-mm1gvpga\"><a href=\"https:\/\/www.redsound.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"200\" class=\"wp-image-643\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\" srcset=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg 350w, https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false,"raw":"<!-- wp:uagb\/container {\"block_id\":\"c4787d8b\",\"directionDesktop\":\"row\",\"backgroundType\":\"color\",\"backgroundColor\":\"\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingTablet\":60,\"bottomPaddingTablet\":60,\"leftPaddingTablet\":30,\"rightPaddingTablet\":30,\"topPaddingMobile\":25,\"bottomPaddingMobile\":25,\"leftPaddingMobile\":25,\"rightPaddingMobile\":25,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"topColor\":\"#eeeeee\",\"topHeight\":50,\"childrenWidthDesktop\":\"equal\"} -->\n<div class=\"wp-block-uagb-container uagb-block-c4787d8b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"5d8c8575\",\"widthDesktop\":60,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-5d8c8575\"><!-- wp:paragraph -->\n<p><strong>AC Acustica<\/strong> offers acoustic design and consulting services in the fields of engineering and architecture, combining international experience and advanced technologies to ensure innovative and precise solutions.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Based in <strong>Ragusa<\/strong>, AC Acustica is led by <strong>Andrea Cicero<\/strong>, who holds a degree in Civil Engineering and a specialization in Acoustics and Audio from the University of Salford. He has many years of experience in the field of acoustics and vibrations, having worked at one of the leading acoustic design and consultancy firms in London, United Kingdom.<\/p>\n<!-- \/wp:paragraph --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"82324d6c\",\"widthDesktop\":40,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-82324d6c\"><!-- wp:image {\"id\":334,\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"style\":{\"border\":{\"radius\":\"10px\"},\"shadow\":\"none\"}} -->\n<figure class=\"wp-block-image size-large has-custom-border\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/andrea-cicero-1024x766.jpg\" alt=\"\" class=\"wp-image-334\" style=\"border-radius:10px;box-shadow:none\"\/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"814f3dd2\",\"directionDesktop\":\"row\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":25,\"bottomPaddingMobile\":25,\"leftPaddingMobile\":25,\"rightPaddingMobile\":25,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"topColor\":\"#f8f8f8\",\"topHeight\":50} -->\n<div class=\"wp-block-uagb-container uagb-block-814f3dd2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"61d2d51f\",\"widthDesktop\":40,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-61d2d51f\"><!-- wp:image {\"id\":344,\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"style\":{\"border\":{\"radius\":\"10px\"},\"shadow\":\"none\"}} -->\n<figure class=\"wp-block-image size-large has-custom-border\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/profilo-1-1024x576.jpg\" alt=\"\" class=\"wp-image-344\" style=\"border-radius:10px;box-shadow:none\"\/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"d17045e1\",\"widthDesktop\":60,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-d17045e1\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"7e559186\",\"classMigrate\":true,\"headingDescToggle\":true,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7e559186\"><h3 class=\"uagb-heading-text\">Awards<\/h3><p class=\"uagb-desc-text\">Italian Acoustical Society \u2018<strong>Young Professionals\u2019 Award 2024<\/strong>, on the occasion of the National Conference in Taormina, for the work <em><a href=\"https:\/\/www.francoangeli.it\/riviste\/articolo\/76817\"><span style=\"text-decoration: underline;\">Acoustic Design of a Modular Studio Box for Use as Control and Mixing Room for Immersive Audio<\/span><\/a><\/em><\/p><\/div>\n<!-- \/wp:uagb\/advanced-heading --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"b4af9fd3\",\"backgroundType\":\"color\",\"backgroundColor\":\"\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"childrenWidthDesktop\":\"equal\"} -->\n<div class=\"wp-block-uagb-container uagb-block-b4af9fd3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"49b0479c\",\"classMigrate\":true,\"headingDescToggle\":true,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-49b0479c\"><h3 class=\"uagb-heading-text\">Technical Skills and Instrumentation<\/h3><p class=\"uagb-desc-text\">AC Acustica is equipped with state-of-the-art certified instrumentation to ensure precise and reliable measurements.<\/p><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"54c0b8e2\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-54c0b8e2\"><h3 class=\"uagb-heading-text\">Acustic Instumentation<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>6 Class 1 sound level meters compliant with IEC 61672<\/strong> for professional measurements in architectural, building, environmental, and industrial acoustics<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>3 accelerometric measurement chains compliant with ISO 8041-1:2017<\/strong> for measurements related to vibration disturbance, building damage assessment, and exposure to mechanical vibrations.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Specialized accessories<\/strong> for long-term acoustic and vibration monitoring<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Impulse response measurement kit<\/strong> dedicated to architectural acoustics<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Calibrated omnidirectional dodecahedral sound source<\/strong> for measurements of sound insulation and room acoustic parameters.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Tapping machine<\/strong> for testing impact sound insulation<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"ef732557\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ef732557\"><h3 class=\"uagb-heading-text\">Specialized software<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>CATT-Acoustic<\/strong> for advanced architectural acoustic modeling<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>iNoise Pro<\/strong> for environmental noise impact assessments<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Insul<\/strong> for sound insulation calculations<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Audieum<\/strong> \u2013 proprietary software for analysis and modeling of critical listening environments<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Custom algorithms<\/strong> for advanced data analysis and process optimization<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"47ae6514\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"topColor\":\"#f8f8f8\",\"topHeight\":50} -->\n<div class=\"wp-block-uagb-container uagb-block-47ae6514 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"041f12c1\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-041f12c1\"><h3 class=\"uagb-heading-text\">Certifications and Affiliations<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Membership in <strong>Ordine degli Ingegneri della Provincia di Ragusa<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Competent Acoustic Technician<\/strong> registered with ENTECA under no. 306<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Member of:<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Audio Engineering Society (AES)<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Institute of Acoustics (IOA)<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Associazione Italiana di Acustica (AIA)<\/strong><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"59970e4e\",\"widthDesktop\":50,\"directionDesktop\":\"row\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-59970e4e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"9d6e21ec\",\"widthDesktop\":60,\"topPaddingDesktop\":0,\"bottomPaddingDesktop\":0,\"leftPaddingDesktop\":0,\"rightPaddingDesktop\":0,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-9d6e21ec\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"68465e67\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-68465e67\"><h3 class=\"uagb-heading-text\">Rete Acustici<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:paragraph -->\n<p>Andrea Cicero is the founder of <strong>Rete Acustici<\/strong> (<a href=\"https:\/\/reteacustici.it\" type=\"link\" id=\"reteacustici.it\">reteacustici.it<\/a>), a <strong>collaborative digital platform<\/strong> that brings together Italian professionals in the field of acoustics. This initiative promotes technical exchange, professional discussion, and mutual support among acoustic consultants, technicians, and engineers, strengthening a nationwide network of specialized expertise.<\/p>\n<!-- \/wp:paragraph --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"570142a0\",\"widthDesktop\":40,\"topPaddingDesktop\":0,\"bottomPaddingDesktop\":0,\"leftPaddingDesktop\":80,\"rightPaddingDesktop\":80,\"paddingLink\":false,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-570142a0\"><!-- wp:image {\"scale\":\"cover\",\"sizeSlug\":\"large\"} -->\n<figure class=\"wp-block-image size-large\"><img src=\"https:\/\/reteacustici.it\/img\/LOGO%20RETE%20ACUSTICI_blu.png\" alt=\"Rete Acustici\" style=\"object-fit:cover\"\/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"69066129\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"childrenWidthDesktop\":\"equal\",\"UAGHideMob\":true,\"UAGResponsiveConditions\":true} -->\n<div class=\"wp-block-uagb-container uag-hide-mob uagb-block-69066129 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"b40c0c24\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b40c0c24\"><h3 class=\"uagb-heading-text\">Partners<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:lcb\/logo-carousel {\"slideStatus\":true,\"images\":[{\"id\":751,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":641,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":642,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":750,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":925,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":1009,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":643,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"}],\"showNav\":false,\"showPagination\":false,\"deskItemsPerView\":5,\"tabItemsPerView\":3,\"phoneItemsPerView\":3,\"deskSpace\":10,\"tabSpace\":10,\"borderWidth\":\"1px\",\"borderColor\":\"#dcdcdc\",\"enableLink\":true,\"logoLinks\":[\"https:\/\/reteacustici.it\",\"https:\/\/www.acusticambientale.com\",\"https:\/\/eupro.it\",\"https:\/\/www.hackustica.it\",\"http:\/\/www.accon.it\",\"https:\/\/sonnite.com\",\"https:\/\/www.redsound.it\"],\"openInNewTab\":true,\"itemPaddingValues\":{\"top\":\"\",\"right\":\"0\",\"bottom\":\"\",\"left\":\"0\"},\"itemPaddingTabValues\":{\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\"},\"itemPaddingIsLinked\":false,\"logobgColor\":\"var(\\u002d\\u002dwp\\u002d\\u002dpreset\\u002d\\u002dcolor\\u002d\\u002dast-global-color-5)\",\"logoPaddingValues\":{\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\"},\"sliderId\":\"alcb-block-lm6khjkq\",\"blockStyle\":\" .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel{ padding-right: 0px; padding-left: 0px;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-item{background-color: var(\\u002d\\u002dwp\\u002d\\u002dpreset\\u002d\\u002dcolor\\u002d\\u002dast-global-color-5);} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-image{padding: 0px;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next:hover, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev:hover{border-color: ;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__pag.swiper-pagination{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-pagination-bullet{ } @media (max-width: 1024px) { .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel{padding-top: 0px; padding-right: 0px; padding-bottom: 0px; padding-left: 0px;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-image{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__pag.swiper-pagination{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-pagination-bullet{ } } @media (max-width: 767px) { .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-image{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__pag.swiper-pagination{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-pagination-bullet{ } } \"} -->\n<div class=\"wp-block-lcb-logo-carousel\"><div dir=\"ltr\" class=\"alcb__carousel_container swiper\" data-desktop=\"5\" data-tablet=\"3\" data-mobile=\"3\" data-autoplay=\"true\" data-autoplaydelay=\"2000\" data-autoplaydirection=\"false\" data-speed=\"400\" data-loop=\"true\" data-pauseonhover=\"true\" data-keyboard=\"false\" data-mousewheel=\"false\" data-autoheight=\"false\" data-deskspace=\"10\" data-tabspace=\"10\" data-phonespace=\"10\" data-id=\"alcb-block-lm6khjkq\" data-pagination=\"false\" data-navigation=\"false\" id=\"alcb-block-lm6khjkq\"><div class=\"swiper-wrapper\"><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/reteacustici.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\" alt=\"\" id=\"751\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.acusticambientale.com\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\" alt=\"\" id=\"641\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/eupro.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\" alt=\"\" id=\"642\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.hackustica.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\" alt=\"\" id=\"750\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"http:\/\/www.accon.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\" alt=\"\" id=\"925\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/sonnite.com\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\" alt=\"\" id=\"1009\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.redsound.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\" alt=\"\" id=\"643\"\/><\/div><\/a><\/div><\/div><\/div>\n<!-- \/wp:lcb\/logo-carousel --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"4a35580c\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"childrenWidthDesktop\":\"equal\",\"UAGHideDesktop\":true,\"UAGHideTab\":true,\"UAGResponsiveConditions\":true} -->\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-4a35580c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"5cda3c4b\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5cda3c4b\"><h3 class=\"uagb-heading-text\">Partners<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:lcb\/grid-logo {\"images\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":751,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/reteacustici\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":641,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/acustica-ambientale-3\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":642,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/eupro\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":750,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/hackustica\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":925,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/accon\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1016,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/sonnite-2\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":643,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/redsound\",\"caption\":\"\"}],\"enableLink\":true,\"gridColRanges\":{\"desk\":6,\"tab\":\"\",\"mob\":3},\"gridGapRanges\":{\"desk\":10,\"tab\":\"\",\"mob\":3},\"alcb_logoBorderColors\":{\"normal\":\"#dcdcdc\",\"hover\":\"\"},\"alcb_logoBorderValues\":{\"top\":\"\",\"right\":\"\",\"bottom\":\"\",\"left\":\"\"},\"alcb_logoBorderMobValues\":{\"top\":\"1\",\"right\":\"1\",\"bottom\":\"1\",\"left\":\"1\"},\"logoHoverBgbgColor\":\"#dcdcdc\",\"className\":\"grid-logos\",\"sliderId\":\"alcb-block-af92yq7u\",\"blockStyle\":\" .alcb-block-af92yq7u .gallery-inner{grid-template-columns:repeat(6, 1fr);gap:10px;} .alcb-block-af92yq7u .logo-wrapper{ background-color: #dcdcdc;} .alcb-block-af92yq7u.wp-block-lcb-grid-logo .logo-content{ } .alcb-block-af92yq7u .alcb__logo-caption { } .alcb-block-af92yq7u .alcb__logo-description { } .alcb-block-af92yq7u .logo-content { } @media (max-width: 1024px) { .alcb-block-af92yq7u .logo-wrapper{ } .alcb-block-af92yq7u.wp-block-lcb-grid-logo .logo-content{ } .alcb-block-af92yq7u .alcb__logo-caption { } .alcb-block-af92yq7u .alcb__logo-description { } .alcb-block-af92yq7u .logo-content { } } @media (max-width: 767px) { .alcb-block-af92yq7u .gallery-inner{grid-template-columns:repeat(3, 1fr);gap:3px;} .alcb-block-af92yq7u .logo-wrapper{border-color: #dcdcdc; border-width: 1px; border-style: none; } .alcb-block-af92yq7u.wp-block-lcb-grid-logo .logo-content{ } .alcb-block-af92yq7u .alcb__logo-caption { } .alcb-block-af92yq7u .alcb__logo-description { } .alcb-block-af92yq7u .logo-content { } } \"} -->\n<div class=\"wp-block-lcb-grid-logo alcb-block-af92yq7u grid-logos\"><div class=\"gallery-inner\"><!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":751,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/reteacustici\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/reteacustici.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-sekgmses\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-sekgmses\"><a href=\"https:\/\/reteacustici.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-751\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":641,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/acustica-ambientale-3\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/www.acusticambientale.com\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-46fx8plw\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-46fx8plw\"><a href=\"https:\/\/www.acusticambientale.com\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-641\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":642,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/eupro\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/eupro.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-0bhryuli\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-0bhryuli\"><a href=\"https:\/\/eupro.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-642\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":750,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/hackustica\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/www.hackustica.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-q9pyvor4\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-q9pyvor4\"><a href=\"https:\/\/www.hackustica.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-750\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":925,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/accon\",\"caption\":\"\"},\"link\":{\"url\":\"http:\/\/www.accon.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-ghnx2530\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-ghnx2530\"><a href=\"http:\/\/www.accon.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-925\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1016,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/sonnite-2\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/sonnite.com\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-29ok4l8i\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-29ok4l8i\"><a href=\"https:\/\/sonnite.com\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-1016\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":643,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/redsound\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/www.redsound.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-mm1gvpga\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-mm1gvpga\"><a href=\"https:\/\/www.redsound.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-643\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo --><\/div><\/div>\n<!-- \/wp:lcb\/grid-logo --><\/div><\/div>\n<!-- \/wp:uagb\/container -->"},"excerpt":{"rendered":"","protected":false,"raw":""},"author":1,"featured_media":317,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","_it_post_content":"<!-- wp:uagb\/container {\"block_id\":\"c4787d8b\",\"directionDesktop\":\"row\",\"backgroundType\":\"color\",\"backgroundColor\":\"\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingTablet\":60,\"bottomPaddingTablet\":60,\"leftPaddingTablet\":30,\"rightPaddingTablet\":30,\"topPaddingMobile\":25,\"bottomPaddingMobile\":25,\"leftPaddingMobile\":25,\"rightPaddingMobile\":25,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"topColor\":\"#eeeeee\",\"topHeight\":50,\"childrenWidthDesktop\":\"equal\"} -->\n<div class=\"wp-block-uagb-container uagb-block-c4787d8b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"5d8c8575\",\"widthDesktop\":60,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-5d8c8575\"><!-- wp:paragraph -->\n<p><strong>AC Acustica<\/strong> propone servizi di progettazione e consulenza acustica nell'ambito dell'ingegneria e dell'architettura, combinando esperienza internazionale e tecnologie avanzate per garantire soluzioni innovative e precise.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Con sede a <strong>Ragusa<\/strong>, AC Acustica \u00e8 diretta da <strong>Andrea Cicero<\/strong>, laureato in Ingegneria Civile e specializzato in Acustica e Audio presso la University of Salford, con esperienza pluriennale nel campo dell'acustica e delle vibrazioni, avendo esercitato presso uno degli studi leader di progettazione e consulenza acustica a Londra, Regno Unito.<\/p>\n<!-- \/wp:paragraph --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"82324d6c\",\"widthDesktop\":40,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-82324d6c\"><!-- wp:image {\"id\":1126,\"width\":\"348px\",\"height\":\"auto\",\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"align\":\"center\",\"className\":\"is-style-default\",\"style\":{\"border\":{\"radius\":\"10px\",\"width\":\"0px\",\"style\":\"none\"},\"shadow\":\"none\"}} -->\n<figure class=\"wp-block-image aligncenter size-large is-resized has-custom-border is-style-default\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/08\/andrea-c-1024x1024.png\" alt=\"\" class=\"wp-image-1126\" style=\"border-style:none;border-width:0px;border-radius:10px;box-shadow:none;width:348px;height:auto\"\/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"814f3dd2\",\"directionDesktop\":\"row\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":25,\"bottomPaddingMobile\":25,\"leftPaddingMobile\":25,\"rightPaddingMobile\":25,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"topColor\":\"#f8f8f8\",\"topHeight\":50} -->\n<div class=\"wp-block-uagb-container uagb-block-814f3dd2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"61d2d51f\",\"widthDesktop\":40,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-61d2d51f\"><!-- wp:image {\"id\":344,\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"style\":{\"border\":{\"radius\":\"10px\"},\"shadow\":\"none\"}} -->\n<figure class=\"wp-block-image size-large has-custom-border\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/profilo-1-1024x576.jpg\" alt=\"\" class=\"wp-image-344\" style=\"border-radius:10px;box-shadow:none\"\/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"d17045e1\",\"widthDesktop\":60,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-d17045e1\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"7e559186\",\"classMigrate\":true,\"headingDescToggle\":true,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7e559186\"><h3 class=\"uagb-heading-text\">Riconoscimenti<\/h3><p class=\"uagb-desc-text\">Premio Associazione Italiana di Acustica <strong>\u00abGiovani Professionisti\u00bb 2024<\/strong>, in occasione del Convegno Nazionale a Taormina, per il lavoro <em><a href=\"https:\/\/www.francoangeli.it\/riviste\/articolo\/76817\"><span style=\"text-decoration: underline;\">Acoustic Design of a Modular Studio Box for Use as Control and Mixing Room for Immersive Audio<\/span><\/a><\/em><\/p><\/div>\n<!-- \/wp:uagb\/advanced-heading --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"b4af9fd3\",\"backgroundType\":\"color\",\"backgroundColor\":\"\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"childrenWidthDesktop\":\"equal\"} -->\n<div class=\"wp-block-uagb-container uagb-block-b4af9fd3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"49b0479c\",\"classMigrate\":true,\"headingDescToggle\":true,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-49b0479c\"><h3 class=\"uagb-heading-text\">Competenze Tecniche e Strumentazione<\/h3><p class=\"uagb-desc-text\">AC Acustica dispone di strumentazione certificata di ultima generazione per garantire misurazioni precise e affidabili.<\/p><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"54c0b8e2\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-54c0b8e2\"><h3 class=\"uagb-heading-text\">Strumentazione Acustica<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>6 fonometri in Classe 1 IEC 61672<\/strong> per misurazioni professionali in ambito di acustica architettonica, edilizia, ambientale e industriale<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>3 catene accelerometriche conformi a ISO 8041-1:2017<\/strong> per misure relative a disturbo da vibrazione, valutazione danni agli edifici ed esposizione a vibrazioni meccaniche<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Accessori specialistici <\/strong>per monitoraggi acustici e vibrazionali a lungo termine<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Kit per acquisizione risposta all'impulso<\/strong> dedicato all'acustica architettonica<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Sorgente Dodecaedrica omnidirezionale calibrata<\/strong> per misurazioni di isolamento acustico e parametri acustici delle sale<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Macchina per il calpestio<\/strong> per verifiche di isolamento ai rumori di calpestio<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"ef732557\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ef732557\"><h3 class=\"uagb-heading-text\">Software Specialistico<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>CATT-Acoustic<\/strong> per modellazione acustica architettonica avanzata<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>iNoise Pro<\/strong> per valutazioni di impatto acustico ambientale<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Insul<\/strong> per calcoli di isolamento acustico<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong><a href=\"http:\/\/www.audieum.com\">Audieum<\/a><\/strong> - software proprietario per analisi e modellazione di ambienti di ascolto critico<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Algoritmi personalizzati<\/strong> per analisi avanzate dei dati e ottimizzazione dei processi<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"47ae6514\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"topColor\":\"#f8f8f8\",\"topHeight\":50} -->\n<div class=\"wp-block-uagb-container uagb-block-47ae6514 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"041f12c1\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-041f12c1\"><h3 class=\"uagb-heading-text\">Certificazioni e Affiliazioni<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Iscrizione all'<strong>Ordine degli Ingegneri della Provincia di Ragusa<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Tecnico Competente in Acustica<\/strong> iscritto a ENTECA al n. 306<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Membro di:<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Audio Engineering Society (AES)<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Institute of Acoustics (IOA)<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Associazione Italiana di Acustica (AIA)<\/strong><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"59970e4e\",\"widthDesktop\":50,\"directionDesktop\":\"row\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-59970e4e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"9d6e21ec\",\"widthDesktop\":60,\"topPaddingDesktop\":0,\"bottomPaddingDesktop\":0,\"leftPaddingDesktop\":0,\"rightPaddingDesktop\":0,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-9d6e21ec\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"68465e67\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-68465e67\"><h3 class=\"uagb-heading-text\">Rete Acustici<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:paragraph -->\n<p>Andrea Cicero \u00e8 fondatore di <strong>Rete Acustici<\/strong> (<a href=\"https:\/\/reteacustici.it\">reteacustici.it<\/a>), una <strong>piattaforma digitale collaborativa <\/strong>che riunisce i professionisti italiani del settore dell'acustica. Questa iniziativa favorisce lo scambio tecnico, il confronto professionale e il mutuo supporto tra consulenti, tecnici e ingegneri acustici, consolidando una rete di competenze specialistiche a livello nazionale.<\/p>\n<!-- \/wp:paragraph --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"570142a0\",\"widthDesktop\":40,\"topPaddingDesktop\":0,\"bottomPaddingDesktop\":0,\"leftPaddingDesktop\":80,\"rightPaddingDesktop\":80,\"paddingLink\":false,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-570142a0\"><!-- wp:image {\"scale\":\"cover\",\"sizeSlug\":\"large\"} -->\n<figure class=\"wp-block-image size-large\"><img src=\"https:\/\/reteacustici.it\/img\/LOGO%20RETE%20ACUSTICI_blu.png\" alt=\"Rete Acustici\" style=\"object-fit:cover\"\/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"69066129\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"childrenWidthDesktop\":\"equal\",\"UAGHideMob\":true,\"UAGResponsiveConditions\":true} -->\n<div class=\"wp-block-uagb-container uag-hide-mob uagb-block-69066129 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"b40c0c24\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b40c0c24\"><h3 class=\"uagb-heading-text\">Partners<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:lcb\/logo-carousel {\"slideStatus\":true,\"images\":[{\"id\":751,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":641,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":642,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":750,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":925,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":1009,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":643,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"}],\"showNav\":false,\"showPagination\":false,\"deskItemsPerView\":5,\"tabItemsPerView\":3,\"phoneItemsPerView\":3,\"deskSpace\":10,\"tabSpace\":10,\"borderWidth\":\"1px\",\"borderColor\":\"#dcdcdc\",\"enableLink\":true,\"logoLinks\":[\"https:\/\/reteacustici.it\",\"https:\/\/www.acusticambientale.com\",\"https:\/\/eupro.it\",\"https:\/\/www.hackustica.it\",\"http:\/\/www.accon.it\",\"https:\/\/sonnite.com\",\"https:\/\/www.redsound.it\"],\"openInNewTab\":true,\"itemPaddingValues\":{\"top\":\"\",\"right\":\"0\",\"bottom\":\"\",\"left\":\"0\"},\"itemPaddingTabValues\":{\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\"},\"itemPaddingIsLinked\":false,\"logobgColor\":\"var(\\u002d\\u002dwp\\u002d\\u002dpreset\\u002d\\u002dcolor\\u002d\\u002dast-global-color-5)\",\"logoPaddingValues\":{\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\"},\"sliderId\":\"alcb-block-lm6khjkq\",\"blockStyle\":\" .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel{ padding-right: 0px; padding-left: 0px;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-item{background-color: var(\\u002d\\u002dwp\\u002d\\u002dpreset\\u002d\\u002dcolor\\u002d\\u002dast-global-color-5);} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-image{padding: 0px;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next:hover, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev:hover{border-color: ;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__pag.swiper-pagination{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-pagination-bullet{ } @media (max-width: 1024px) { .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel{padding-top: 0px; padding-right: 0px; padding-bottom: 0px; padding-left: 0px;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-image{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__pag.swiper-pagination{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-pagination-bullet{ } } @media (max-width: 767px) { .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-image{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__pag.swiper-pagination{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-pagination-bullet{ } } \"} -->\n<div class=\"wp-block-lcb-logo-carousel\"><div dir=\"ltr\" class=\"alcb__carousel_container swiper\" data-desktop=\"5\" data-tablet=\"3\" data-mobile=\"3\" data-autoplay=\"true\" data-autoplaydelay=\"2000\" data-autoplaydirection=\"false\" data-speed=\"400\" data-loop=\"true\" data-pauseonhover=\"true\" data-keyboard=\"false\" data-mousewheel=\"false\" data-autoheight=\"false\" data-deskspace=\"10\" data-tabspace=\"10\" data-phonespace=\"10\" data-id=\"alcb-block-lm6khjkq\" data-pagination=\"false\" data-navigation=\"false\" id=\"alcb-block-lm6khjkq\"><div class=\"swiper-wrapper\"><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/reteacustici.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\" alt=\"\" id=\"751\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.acusticambientale.com\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\" alt=\"\" id=\"641\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/eupro.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\" alt=\"\" id=\"642\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.hackustica.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\" alt=\"\" id=\"750\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"http:\/\/www.accon.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\" alt=\"\" id=\"925\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/sonnite.com\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\" alt=\"\" id=\"1009\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.redsound.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\" alt=\"\" id=\"643\"\/><\/div><\/a><\/div><\/div><\/div>\n<!-- \/wp:lcb\/logo-carousel --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"4a35580c\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"childrenWidthDesktop\":\"equal\",\"UAGHideDesktop\":true,\"UAGHideTab\":true,\"UAGResponsiveConditions\":true} -->\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-4a35580c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"5cda3c4b\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5cda3c4b\"><h3 class=\"uagb-heading-text\">Partners<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:lcb\/grid-logo {\"images\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":751,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/reteacustici\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":641,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/acustica-ambientale-3\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":642,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/eupro\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":750,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/hackustica\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":925,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/accon\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1016,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/sonnite-2\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":643,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/redsound\",\"caption\":\"\"}],\"enableLink\":true,\"gridColRanges\":{\"desk\":6,\"tab\":\"\",\"mob\":3},\"gridGapRanges\":{\"desk\":10,\"tab\":\"\",\"mob\":3},\"alcb_logoBorderColors\":{\"normal\":\"#dcdcdc\",\"hover\":\"\"},\"alcb_logoBorderValues\":{\"top\":\"\",\"right\":\"\",\"bottom\":\"\",\"left\":\"\"},\"alcb_logoBorderMobValues\":{\"top\":\"1\",\"right\":\"1\",\"bottom\":\"1\",\"left\":\"1\"},\"logoHoverBgbgColor\":\"#dcdcdc\",\"className\":\"grid-logos\",\"sliderId\":\"alcb-block-af92yq7u\",\"blockStyle\":\" .alcb-block-af92yq7u .gallery-inner{grid-template-columns:repeat(6, 1fr);gap:10px;} .alcb-block-af92yq7u .logo-wrapper{ background-color: #dcdcdc;} .alcb-block-af92yq7u.wp-block-lcb-grid-logo .logo-content{ } .alcb-block-af92yq7u .alcb__logo-caption { } .alcb-block-af92yq7u .alcb__logo-description { } .alcb-block-af92yq7u .logo-content { } @media (max-width: 1024px) { .alcb-block-af92yq7u .logo-wrapper{ } .alcb-block-af92yq7u.wp-block-lcb-grid-logo .logo-content{ } .alcb-block-af92yq7u .alcb__logo-caption { } .alcb-block-af92yq7u .alcb__logo-description { } .alcb-block-af92yq7u .logo-content { } } @media (max-width: 767px) { .alcb-block-af92yq7u .gallery-inner{grid-template-columns:repeat(3, 1fr);gap:3px;} .alcb-block-af92yq7u .logo-wrapper{border-color: #dcdcdc; border-width: 1px; border-style: none; } .alcb-block-af92yq7u.wp-block-lcb-grid-logo .logo-content{ } .alcb-block-af92yq7u .alcb__logo-caption { } .alcb-block-af92yq7u .alcb__logo-description { } .alcb-block-af92yq7u .logo-content { } } \"} -->\n<div class=\"wp-block-lcb-grid-logo alcb-block-af92yq7u grid-logos\"><div class=\"gallery-inner\"><!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":751,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/reteacustici\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/reteacustici.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-sekgmses\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-sekgmses\"><a href=\"https:\/\/reteacustici.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-751\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":641,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/acustica-ambientale-3\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/www.acusticambientale.com\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-46fx8plw\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-46fx8plw\"><a href=\"https:\/\/www.acusticambientale.com\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-641\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":642,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/eupro\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/eupro.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-0bhryuli\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-0bhryuli\"><a href=\"https:\/\/eupro.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-642\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":750,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/hackustica\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/www.hackustica.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-q9pyvor4\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-q9pyvor4\"><a href=\"https:\/\/www.hackustica.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-750\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":925,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/accon\",\"caption\":\"\"},\"link\":{\"url\":\"http:\/\/www.accon.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-ghnx2530\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-ghnx2530\"><a href=\"http:\/\/www.accon.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-925\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1016,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/sonnite-2\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/sonnite.com\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-29ok4l8i\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-29ok4l8i\"><a href=\"https:\/\/sonnite.com\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-1016\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":643,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/redsound\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/www.redsound.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-mm1gvpga\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-mm1gvpga\"><a href=\"https:\/\/www.redsound.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-643\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo --><\/div><\/div>\n<!-- \/wp:lcb\/grid-logo --><\/div><\/div>\n<!-- \/wp:uagb\/container -->","_it_post_name":"profilo","_it_post_excerpt":"","_it_post_title":"Profilo","_en_post_content":"<!-- wp:uagb\/container {\"block_id\":\"c4787d8b\",\"directionDesktop\":\"row\",\"backgroundType\":\"color\",\"backgroundColor\":\"\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingTablet\":60,\"bottomPaddingTablet\":60,\"leftPaddingTablet\":30,\"rightPaddingTablet\":30,\"topPaddingMobile\":25,\"bottomPaddingMobile\":25,\"leftPaddingMobile\":25,\"rightPaddingMobile\":25,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"topColor\":\"#eeeeee\",\"topHeight\":50,\"childrenWidthDesktop\":\"equal\"} -->\n<div class=\"wp-block-uagb-container uagb-block-c4787d8b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"5d8c8575\",\"widthDesktop\":60,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-5d8c8575\"><!-- wp:paragraph -->\n<p><strong>AC Acustica<\/strong> offers acoustic design and consulting services in the fields of engineering and architecture, combining international experience and advanced technologies to ensure innovative and precise solutions.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Based in <strong>Ragusa<\/strong>, AC Acustica is led by <strong>Andrea Cicero<\/strong>, who holds a degree in Civil Engineering and a specialization in Acoustics and Audio from the University of Salford. He has many years of experience in the field of acoustics and vibrations, having worked at one of the leading acoustic design and consultancy firms in London, United Kingdom.<\/p>\n<!-- \/wp:paragraph --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"82324d6c\",\"widthDesktop\":40,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-82324d6c\"><!-- wp:image {\"id\":334,\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"style\":{\"border\":{\"radius\":\"10px\"},\"shadow\":\"none\"}} -->\n<figure class=\"wp-block-image size-large has-custom-border\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/andrea-cicero-1024x766.jpg\" alt=\"\" class=\"wp-image-334\" style=\"border-radius:10px;box-shadow:none\"\/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"814f3dd2\",\"directionDesktop\":\"row\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":25,\"bottomPaddingMobile\":25,\"leftPaddingMobile\":25,\"rightPaddingMobile\":25,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"topColor\":\"#f8f8f8\",\"topHeight\":50} -->\n<div class=\"wp-block-uagb-container uagb-block-814f3dd2 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"61d2d51f\",\"widthDesktop\":40,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-61d2d51f\"><!-- wp:image {\"id\":344,\"sizeSlug\":\"large\",\"linkDestination\":\"none\",\"style\":{\"border\":{\"radius\":\"10px\"},\"shadow\":\"none\"}} -->\n<figure class=\"wp-block-image size-large has-custom-border\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/profilo-1-1024x576.jpg\" alt=\"\" class=\"wp-image-344\" style=\"border-radius:10px;box-shadow:none\"\/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"d17045e1\",\"widthDesktop\":60,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-d17045e1\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"7e559186\",\"classMigrate\":true,\"headingDescToggle\":true,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7e559186\"><h3 class=\"uagb-heading-text\">Awards<\/h3><p class=\"uagb-desc-text\">Italian Acoustical Society \u2018<strong>Young Professionals\u2019 Award 2024<\/strong>, on the occasion of the National Conference in Taormina, for the work <em><a href=\"https:\/\/www.francoangeli.it\/riviste\/articolo\/76817\"><span style=\"text-decoration: underline;\">Acoustic Design of a Modular Studio Box for Use as Control and Mixing Room for Immersive Audio<\/span><\/a><\/em><\/p><\/div>\n<!-- \/wp:uagb\/advanced-heading --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"b4af9fd3\",\"backgroundType\":\"color\",\"backgroundColor\":\"\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"childrenWidthDesktop\":\"equal\"} -->\n<div class=\"wp-block-uagb-container uagb-block-b4af9fd3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"49b0479c\",\"classMigrate\":true,\"headingDescToggle\":true,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-49b0479c\"><h3 class=\"uagb-heading-text\">Technical Skills and Instrumentation<\/h3><p class=\"uagb-desc-text\">AC Acustica is equipped with state-of-the-art certified instrumentation to ensure precise and reliable measurements.<\/p><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"54c0b8e2\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-54c0b8e2\"><h3 class=\"uagb-heading-text\">Acustic Instumentation<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>6 Class 1 sound level meters compliant with IEC 61672<\/strong> for professional measurements in architectural, building, environmental, and industrial acoustics<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>3 accelerometric measurement chains compliant with ISO 8041-1:2017<\/strong> for measurements related to vibration disturbance, building damage assessment, and exposure to mechanical vibrations.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Specialized accessories<\/strong> for long-term acoustic and vibration monitoring<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Impulse response measurement kit<\/strong> dedicated to architectural acoustics<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Calibrated omnidirectional dodecahedral sound source<\/strong> for measurements of sound insulation and room acoustic parameters.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Tapping machine<\/strong> for testing impact sound insulation<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:uagb\/advanced-heading {\"block_id\":\"ef732557\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ef732557\"><h3 class=\"uagb-heading-text\">Specialized software<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>CATT-Acoustic<\/strong> for advanced architectural acoustic modeling<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>iNoise Pro<\/strong> for environmental noise impact assessments<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Insul<\/strong> for sound insulation calculations<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Audieum<\/strong> \u2013 proprietary software for analysis and modeling of critical listening environments<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Custom algorithms<\/strong> for advanced data analysis and process optimization<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"47ae6514\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"topColor\":\"#f8f8f8\",\"topHeight\":50} -->\n<div class=\"wp-block-uagb-container uagb-block-47ae6514 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"041f12c1\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-041f12c1\"><h3 class=\"uagb-heading-text\">Certifications and Affiliations<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Membership in <strong>Ordine degli Ingegneri della Provincia di Ragusa<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Competent Acoustic Technician<\/strong> registered with ENTECA under no. 306<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Member of:<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Audio Engineering Society (AES)<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Institute of Acoustics (IOA)<\/strong><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Associazione Italiana di Acustica (AIA)<\/strong><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"59970e4e\",\"widthDesktop\":50,\"directionDesktop\":\"row\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"paddingLink\":false,\"variationSelected\":true,\"isBlockRootParent\":true,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-59970e4e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/container {\"block_id\":\"9d6e21ec\",\"widthDesktop\":60,\"topPaddingDesktop\":0,\"bottomPaddingDesktop\":0,\"leftPaddingDesktop\":0,\"rightPaddingDesktop\":0,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-9d6e21ec\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"68465e67\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-68465e67\"><h3 class=\"uagb-heading-text\">Rete Acustici<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:paragraph -->\n<p>Andrea Cicero is the founder of <strong>Rete Acustici<\/strong> (<a href=\"https:\/\/reteacustici.it\" type=\"link\" id=\"reteacustici.it\">reteacustici.it<\/a>), a <strong>collaborative digital platform<\/strong> that brings together Italian professionals in the field of acoustics. This initiative promotes technical exchange, professional discussion, and mutual support among acoustic consultants, technicians, and engineers, strengthening a nationwide network of specialized expertise.<\/p>\n<!-- \/wp:paragraph --><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"570142a0\",\"widthDesktop\":40,\"topPaddingDesktop\":0,\"bottomPaddingDesktop\":0,\"leftPaddingDesktop\":80,\"rightPaddingDesktop\":80,\"paddingLink\":false,\"widthSetByUser\":true} -->\n<div class=\"wp-block-uagb-container uagb-block-570142a0\"><!-- wp:image {\"scale\":\"cover\",\"sizeSlug\":\"large\"} -->\n<figure class=\"wp-block-image size-large\"><img src=\"https:\/\/reteacustici.it\/img\/LOGO%20RETE%20ACUSTICI_blu.png\" alt=\"Rete Acustici\" style=\"object-fit:cover\"\/><\/figure>\n<!-- \/wp:image --><\/div>\n<!-- \/wp:uagb\/container --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"69066129\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"childrenWidthDesktop\":\"equal\",\"UAGHideMob\":true,\"UAGResponsiveConditions\":true} -->\n<div class=\"wp-block-uagb-container uag-hide-mob uagb-block-69066129 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"b40c0c24\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b40c0c24\"><h3 class=\"uagb-heading-text\">Partners<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:lcb\/logo-carousel {\"slideStatus\":true,\"images\":[{\"id\":751,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":641,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":642,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":750,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":925,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":1009,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"},{\"id\":643,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"alt\":\"\",\"caption\":\"\",\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"customLink\":\"\"}],\"showNav\":false,\"showPagination\":false,\"deskItemsPerView\":5,\"tabItemsPerView\":3,\"phoneItemsPerView\":3,\"deskSpace\":10,\"tabSpace\":10,\"borderWidth\":\"1px\",\"borderColor\":\"#dcdcdc\",\"enableLink\":true,\"logoLinks\":[\"https:\/\/reteacustici.it\",\"https:\/\/www.acusticambientale.com\",\"https:\/\/eupro.it\",\"https:\/\/www.hackustica.it\",\"http:\/\/www.accon.it\",\"https:\/\/sonnite.com\",\"https:\/\/www.redsound.it\"],\"openInNewTab\":true,\"itemPaddingValues\":{\"top\":\"\",\"right\":\"0\",\"bottom\":\"\",\"left\":\"0\"},\"itemPaddingTabValues\":{\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\"},\"itemPaddingIsLinked\":false,\"logobgColor\":\"var(\\u002d\\u002dwp\\u002d\\u002dpreset\\u002d\\u002dcolor\\u002d\\u002dast-global-color-5)\",\"logoPaddingValues\":{\"top\":\"0\",\"right\":\"0\",\"bottom\":\"0\",\"left\":\"0\"},\"sliderId\":\"alcb-block-lm6khjkq\",\"blockStyle\":\" .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel{ padding-right: 0px; padding-left: 0px;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-item{background-color: var(\\u002d\\u002dwp\\u002d\\u002dpreset\\u002d\\u002dcolor\\u002d\\u002dast-global-color-5);} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-image{padding: 0px;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next:hover, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev:hover{border-color: ;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__pag.swiper-pagination{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-pagination-bullet{ } @media (max-width: 1024px) { .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel{padding-top: 0px; padding-right: 0px; padding-bottom: 0px; padding-left: 0px;} .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-image{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__pag.swiper-pagination{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-pagination-bullet{ } } @media (max-width: 767px) { .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__logo-image{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-next, .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-button-prev{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .alcb__pag.swiper-pagination{ } .alcb-block-lm6khjkq.wp-block-lcb-logo-carousel .swiper-pagination-bullet{ } } \"} -->\n<div class=\"wp-block-lcb-logo-carousel\"><div dir=\"ltr\" class=\"alcb__carousel_container swiper\" data-desktop=\"5\" data-tablet=\"3\" data-mobile=\"3\" data-autoplay=\"true\" data-autoplaydelay=\"2000\" data-autoplaydirection=\"false\" data-speed=\"400\" data-loop=\"true\" data-pauseonhover=\"true\" data-keyboard=\"false\" data-mousewheel=\"false\" data-autoheight=\"false\" data-deskspace=\"10\" data-tabspace=\"10\" data-phonespace=\"10\" data-id=\"alcb-block-lm6khjkq\" data-pagination=\"false\" data-navigation=\"false\" id=\"alcb-block-lm6khjkq\"><div class=\"swiper-wrapper\"><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/reteacustici.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\" alt=\"\" id=\"751\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.acusticambientale.com\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\" alt=\"\" id=\"641\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/eupro.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\" alt=\"\" id=\"642\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.hackustica.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\" alt=\"\" id=\"750\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"http:\/\/www.accon.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\" alt=\"\" id=\"925\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/sonnite.com\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite.jpg\" alt=\"\" id=\"1009\"\/><\/div><\/a><a class=\"swiper-slide alcb__logo-item\" style=\"border: 1px solid #dcdcdc;border-radius:0px\" href=\"https:\/\/www.redsound.it\" target=\"_blank\" rel=\"noopener noreferrer\"><div class=\"alcb__logo-image  alcb__none\"><img src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\" alt=\"\" id=\"643\"\/><\/div><\/a><\/div><\/div><\/div>\n<!-- \/wp:lcb\/logo-carousel --><\/div><\/div>\n<!-- \/wp:uagb\/container -->\n\n<!-- wp:uagb\/container {\"block_id\":\"4a35580c\",\"backgroundType\":\"color\",\"backgroundColor\":\"#eeeeee\",\"topPaddingDesktop\":60,\"bottomPaddingDesktop\":60,\"leftPaddingDesktop\":30,\"rightPaddingDesktop\":30,\"topPaddingMobile\":35,\"bottomPaddingMobile\":35,\"leftPaddingMobile\":35,\"rightPaddingMobile\":35,\"paddingLink\":false,\"topMarginDesktop\":0,\"bottomMarginDesktop\":0,\"leftMarginDesktop\":0,\"rightMarginDesktop\":0,\"variationSelected\":true,\"isBlockRootParent\":true,\"childrenWidthDesktop\":\"equal\",\"UAGHideDesktop\":true,\"UAGHideTab\":true,\"UAGResponsiveConditions\":true} -->\n<div class=\"wp-block-uagb-container uag-hide-desktop uag-hide-tab uagb-block-4a35580c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><!-- wp:uagb\/advanced-heading {\"block_id\":\"5cda3c4b\",\"classMigrate\":true,\"headingDescToggle\":false,\"headingTag\":\"h3\"} -->\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5cda3c4b\"><h3 class=\"uagb-heading-text\">Partners<\/h3><\/div>\n<!-- \/wp:uagb\/advanced-heading -->\n\n<!-- wp:lcb\/grid-logo {\"images\":[{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":751,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/reteacustici\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":641,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/acustica-ambientale-3\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":642,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/eupro\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":750,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/hackustica\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":925,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/accon\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1016,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/sonnite-2\",\"caption\":\"\"},{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":643,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/redsound\",\"caption\":\"\"}],\"enableLink\":true,\"gridColRanges\":{\"desk\":6,\"tab\":\"\",\"mob\":3},\"gridGapRanges\":{\"desk\":10,\"tab\":\"\",\"mob\":3},\"alcb_logoBorderColors\":{\"normal\":\"#dcdcdc\",\"hover\":\"\"},\"alcb_logoBorderValues\":{\"top\":\"\",\"right\":\"\",\"bottom\":\"\",\"left\":\"\"},\"alcb_logoBorderMobValues\":{\"top\":\"1\",\"right\":\"1\",\"bottom\":\"1\",\"left\":\"1\"},\"logoHoverBgbgColor\":\"#dcdcdc\",\"className\":\"grid-logos\",\"sliderId\":\"alcb-block-af92yq7u\",\"blockStyle\":\" .alcb-block-af92yq7u .gallery-inner{grid-template-columns:repeat(6, 1fr);gap:10px;} .alcb-block-af92yq7u .logo-wrapper{ background-color: #dcdcdc;} .alcb-block-af92yq7u.wp-block-lcb-grid-logo .logo-content{ } .alcb-block-af92yq7u .alcb__logo-caption { } .alcb-block-af92yq7u .alcb__logo-description { } .alcb-block-af92yq7u .logo-content { } @media (max-width: 1024px) { .alcb-block-af92yq7u .logo-wrapper{ } .alcb-block-af92yq7u.wp-block-lcb-grid-logo .logo-content{ } .alcb-block-af92yq7u .alcb__logo-caption { } .alcb-block-af92yq7u .alcb__logo-description { } .alcb-block-af92yq7u .logo-content { } } @media (max-width: 767px) { .alcb-block-af92yq7u .gallery-inner{grid-template-columns:repeat(3, 1fr);gap:3px;} .alcb-block-af92yq7u .logo-wrapper{border-color: #dcdcdc; border-width: 1px; border-style: none; } .alcb-block-af92yq7u.wp-block-lcb-grid-logo .logo-content{ } .alcb-block-af92yq7u .alcb__logo-caption { } .alcb-block-af92yq7u .alcb__logo-description { } .alcb-block-af92yq7u .logo-content { } } \"} -->\n<div class=\"wp-block-lcb-grid-logo alcb-block-af92yq7u grid-logos\"><div class=\"gallery-inner\"><!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":751,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/reteacustici\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/reteacustici.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-sekgmses\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-sekgmses\"><a href=\"https:\/\/reteacustici.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-751\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/reteacustici.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":641,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/acustica-ambientale-3\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/www.acusticambientale.com\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-46fx8plw\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-46fx8plw\"><a href=\"https:\/\/www.acusticambientale.com\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-641\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-ambientale-1.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":642,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/eupro\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/eupro.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-0bhryuli\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-0bhryuli\"><a href=\"https:\/\/eupro.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-642\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/eupro.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":750,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/hackustica\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/www.hackustica.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-q9pyvor4\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-q9pyvor4\"><a href=\"https:\/\/www.hackustica.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-750\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/hackustica.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":925,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/accon\",\"caption\":\"\"},\"link\":{\"url\":\"http:\/\/www.accon.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-ghnx2530\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-ghnx2530\"><a href=\"http:\/\/www.accon.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-925\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/11\/accon.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":1016,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/sonnite-2\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/sonnite.com\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-29ok4l8i\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-29ok4l8i\"><a href=\"https:\/\/sonnite.com\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-1016\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2026\/05\/sonnite-1.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo -->\n\n<!-- wp:lcb\/logo {\"photo\":{\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":171,\"width\":300,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound-300x171.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"height\":200,\"width\":350,\"orientation\":\"landscape\"}},\"mime\":\"image\/jpeg\",\"type\":\"image\",\"subtype\":\"jpeg\",\"id\":643,\"url\":\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\",\"alt\":\"\",\"link\":\"https:\/\/www.ac-acustica.it\/profilo\/redsound\",\"caption\":\"\"},\"link\":{\"url\":\"https:\/\/www.redsound.it\",\"openInNewTab\":true},\"enableLink\":true,\"sliderId\":\"alcb-block-mm1gvpga\"} -->\n<div class=\"wp-block-lcb-logo alcb-block-mm1gvpga\"><a href=\"https:\/\/www.redsound.it\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"logo-wrapper\"><div class=\"logo-img\"><img class=\"wp-image-643\" src=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/redsound.jpg\"\/><\/div><div class=\"logo-content\"><\/div><\/a><\/div>\n<!-- \/wp:lcb\/logo --><\/div><\/div>\n<!-- \/wp:lcb\/grid-logo --><\/div><\/div>\n<!-- \/wp:uagb\/container -->","_en_post_name":"about","_en_post_excerpt":"","_en_post_title":"About","edit_language":"en","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-35","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profilo | AC Acustica<\/title>\n<meta name=\"description\" content=\"Andrea Cicero, tecnico competente in acustica abilitato. Consulenza specializzata in acustica, rumore e vibrazioni con sede a Ragusa, Sicilia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ac-acustica.it\/profilo\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profilo | AC Acustica\" \/>\n<meta property=\"og:description\" content=\"Andrea Cicero, tecnico competente in acustica abilitato. Consulenza specializzata in acustica, rumore e vibrazioni con sede a Ragusa, Sicilia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ac-acustica.it\/profilo\" \/>\n<meta property=\"og:site_name\" content=\"AC Acustica\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-06T12:41:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/profilo\",\"url\":\"https:\\\/\\\/www.ac-acustica.it\\\/profilo\",\"name\":\"Profilo | AC Acustica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/profilo#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/profilo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ac-acustica.it\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/acustica-architettonica.jpeg\",\"datePublished\":\"2025-09-01T17:17:58+00:00\",\"dateModified\":\"2026-08-06T12:41:16+00:00\",\"description\":\"Andrea Cicero, tecnico competente in acustica abilitato. Consulenza specializzata in acustica, rumore e vibrazioni con sede a Ragusa, Sicilia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/profilo#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ac-acustica.it\\\/profilo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/profilo#primaryimage\",\"url\":\"https:\\\/\\\/www.ac-acustica.it\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/acustica-architettonica.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ac-acustica.it\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/acustica-architettonica.jpeg\",\"width\":800,\"height\":600,\"caption\":\"Progettazione e misure acustiche\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/profilo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ac-acustica.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profilo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/#website\",\"url\":\"https:\\\/\\\/www.ac-acustica.it\\\/\",\"name\":\"AC Acustica\",\"description\":\"Progettazione e Consulenza Acustica\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ac-acustica.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/#organization\",\"name\":\"AC Acustica\",\"url\":\"https:\\\/\\\/www.ac-acustica.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ac-acustica.it\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-ac.svg\",\"contentUrl\":\"https:\\\/\\\/www.ac-acustica.it\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-ac.svg\",\"width\":1496,\"height\":507,\"caption\":\"AC Acustica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ac-acustica.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profilo | AC Acustica","description":"Andrea Cicero, tecnico competente in acustica abilitato. Consulenza specializzata in acustica, rumore e vibrazioni con sede a Ragusa, Sicilia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ac-acustica.it\/profilo","og_locale":"en_GB","og_type":"article","og_title":"Profilo | AC Acustica","og_description":"Andrea Cicero, tecnico competente in acustica abilitato. Consulenza specializzata in acustica, rumore e vibrazioni con sede a Ragusa, Sicilia.","og_url":"https:\/\/www.ac-acustica.it\/profilo","og_site_name":"AC Acustica","article_modified_time":"2026-08-06T12:41:16+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ac-acustica.it\/profilo","url":"https:\/\/www.ac-acustica.it\/profilo","name":"Profilo | AC Acustica","isPartOf":{"@id":"https:\/\/www.ac-acustica.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ac-acustica.it\/profilo#primaryimage"},"image":{"@id":"https:\/\/www.ac-acustica.it\/profilo#primaryimage"},"thumbnailUrl":"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica.jpeg","datePublished":"2025-09-01T17:17:58+00:00","dateModified":"2026-08-06T12:41:16+00:00","description":"Andrea Cicero, tecnico competente in acustica abilitato. Consulenza specializzata in acustica, rumore e vibrazioni con sede a Ragusa, Sicilia.","breadcrumb":{"@id":"https:\/\/www.ac-acustica.it\/profilo#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ac-acustica.it\/profilo"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ac-acustica.it\/profilo#primaryimage","url":"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica.jpeg","contentUrl":"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica.jpeg","width":800,"height":600,"caption":"Progettazione e misure acustiche"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ac-acustica.it\/profilo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ac-acustica.it\/"},{"@type":"ListItem","position":2,"name":"Profilo"}]},{"@type":"WebSite","@id":"https:\/\/www.ac-acustica.it\/#website","url":"https:\/\/www.ac-acustica.it\/","name":"AC Acustica","description":"Progettazione e Consulenza Acustica","publisher":{"@id":"https:\/\/www.ac-acustica.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ac-acustica.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.ac-acustica.it\/#organization","name":"AC Acustica","url":"https:\/\/www.ac-acustica.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ac-acustica.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/logo-ac.svg","contentUrl":"https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/logo-ac.svg","width":1496,"height":507,"caption":"AC Acustica"},"image":{"@id":"https:\/\/www.ac-acustica.it\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica.jpeg",800,600,false],"thumbnail":["https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica-150x150.jpeg",150,150,true],"medium":["https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica-300x225.jpeg",300,225,true],"medium_large":["https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica-768x576.jpeg",768,576,true],"large":["https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica.jpeg",800,600,false],"1536x1536":["https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica.jpeg",800,600,false],"2048x2048":["https:\/\/www.ac-acustica.it\/wp-content\/uploads\/2025\/09\/acustica-architettonica.jpeg",800,600,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.ac-acustica.it\/en\/author\/admin"},"uagb_comment_info":0,"uagb_excerpt":"AC Acustica propone servizi di progettazione e consulenza acustica nell&#8217;ambito dell&#8217;ingegneria e dell&#8217;architettura, combinando esperienza internazionale e tecnologie avanzate per [&hellip;]","_links":{"self":[{"href":"https:\/\/www.ac-acustica.it\/en\/wp-json\/wp\/v2\/pages\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ac-acustica.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ac-acustica.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ac-acustica.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ac-acustica.it\/en\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":139,"href":"https:\/\/www.ac-acustica.it\/en\/wp-json\/wp\/v2\/pages\/35\/revisions"}],"predecessor-version":[{"id":1129,"href":"https:\/\/www.ac-acustica.it\/en\/wp-json\/wp\/v2\/pages\/35\/revisions\/1129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ac-acustica.it\/en\/wp-json\/wp\/v2\/media\/317"}],"wp:attachment":[{"href":"https:\/\/www.ac-acustica.it\/en\/wp-json\/wp\/v2\/media?parent=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}